{"id":256,"date":"2024-10-01T21:08:46","date_gmt":"2025-05-11T13:16:11","guid":{"rendered":"https:\/\/info-coches.com\/bastidor\/index.php\/2022\/02\/09\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/"},"modified":"2022-02-18T18:35:10","modified_gmt":"2022-02-18T18:35:10","slug":"donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l","status":"publish","type":"post","link":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/","title":{"rendered":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l"},"content":{"rendered":"<p>El n\u00famero de Chasis, n\u00famero de bastidor o <strong>VIN es un c\u00f3digo de identificaci\u00f3n \u00fanico para su Ford Taurus l<\/strong>, mediante el cual los fabricantes Ford y pueden identificar a nivel mundial sus unidades producidas y con las cual las agencias estatales pueden realizar un seguimiento del mismo.<\/p>\n<p>\ud83d\ude97<\/p>\n<p>Este n\u00famero se utiliza generar un informe \u00fanico para un veh\u00edculo Ford Taurus l espec\u00edfico\u00a0 a nivel mundial, y as\u00ed poder realizar un seguimiento y un registro de todos sus datos y cambios. He de ah\u00ed la importancia de este c\u00f3digo.<\/p>\n<p>En nuestra web le indicaremos donde puedes encontrar el n\u00famero de bastidor o n\u00famero de chasis, en el modelo de veh\u00edculo Ford Taurus l.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00bfD\u00f3nde encontrar el n\u00famero de bastidor en la ficha t\u00e9cnica del Ford Taurus l?<\/h3>\n<p>En n\u00famero de chasis del Taurus l as\u00ed como el de todos los vehiculo lo puedes encontrar en la ficha de T\u00e9cnica del Veh\u00edculo,<\/p>\n<ul>\n<li>En el modelo antiguo de la\u00a0<strong>ITV<\/strong>\u00a0Inspecci\u00f3n T\u00e9cnica de Veh\u00edculos, el\u00a0<strong>n\u00famero de bastidor del Ford Taurus l <\/strong>se encuentra en el apartado \u201c<strong>N\u00b0 de identificaci\u00f3n<\/strong>\u201d.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>En el nuevo formato de ITV electr\u00f3nico, o e ITV, se puede encontrar en n\u00famero de bastidor o n\u00famero de <strong>chasis del Taurus l en el campo \u201cE\u201d<\/strong>.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>\u00bfD\u00f3nde encontrar el n\u00famero de bastidor del Ford Taurus l en el coche?<\/h3>\n<p>Es importante asegurarse de que el c\u00f3digo VIN cuente con los 17 d\u00edgitos, teniendo en cuenta que estos no deben incluir los caracteres I, O, Q ni \u00d1.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><img decoding=\"async\" class=\"size-medium alignleft\" title=\"N\u00famero de bastidor Ford Taurus l\" src=\"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-300x195.jpg\" alt=\"N\u00famero de bastidor Ford Taurus l\" width=\"300\" height=\"195\" \/><\/p>\n<h3 class=\"LC20lb MBeuO DKV0Md\">\u2713\u00a0 El n\u00famero de bastidor o n\u00famero de chasis tambi\u00e9n se encuentra en mismo coche Ford Taurus l, m\u00e1s concretamente,\u00a0 grabado en el larguero derecho (visto de frente).<\/h3>\n<h6>Se trata de con 17 d\u00edgitos compuestos con letras y n\u00fameros. Si tiene menos de 17 d\u00edgitos significar\u00eda que su modelo de Ford Taurus l es anterior a 1981<\/h6>\n<\/blockquote>\n<p><em>*Hay que tener en cuenta que debido\u00a0 su ubicaci\u00f3n, muchas veces, se puede encontrar manchado de polvo o grasa y no es f\u00e1cil de ver.\u00a0<\/em><\/p>\n<p><strong>Es crucial, si quieres realizar la compra de un veh\u00edculo Taurus l, verificar que el n\u00famero de bastidor que indica la ficha t\u00e9cnica del\u00a0 Ford Taurus l y el que aparece en el chasis sea el mismo para comprobar que todo es correcto.<\/strong><\/p>\n<p>Gracias al n\u00famero de bastidor o n\u00famero de chasis puedes comprobar que el veh\u00edculo Ford Taurus l procede de una fuente fiable y que est\u00e1 al d\u00eda con la ley.<\/p>\n<p>Tambi\u00e9n puedes revisar que los kil\u00f3metros del cuentakil\u00f3metros del Taurus l coincidan con los de la ficha t\u00e9cnica del veh\u00edculo Ford Taurus l.<\/p>\n<p>Para m\u00e1s seguridad puedes solicitar en la DGT un historial del veh\u00edculo Ford Taurus l antes de adquirirlo, para verificar que todo est\u00e1 en regla y que no est\u00e1 siendo v\u00edctima de un fraude.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El n\u00famero de Chasis, n\u00famero de bastidor o VIN es un c\u00f3digo de identificaci\u00f3n \u00fanico para su Ford Taurus l, mediante el cual los fabricantes [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":794,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-numero-de-bastidor-de-ford"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l<\/title>\n<meta name=\"description\" content=\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l \u00bfD\u00f3nde se encuentra el n\u00famero de bastidor o n\u00famero de chasis de tu coche?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l\" \/>\n<meta property=\"og:description\" content=\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l \u00bfD\u00f3nde se encuentra el n\u00famero de bastidor o n\u00famero de chasis de tu coche?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/\" \/>\n<meta property=\"og:site_name\" content=\"Informaci\u00f3n b\u00e1stidor\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-11T13:16:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"971\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"buyhouseweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"buyhouseweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/\"},\"author\":{\"name\":\"buyhouseweb\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#\\\/schema\\\/person\\\/db138b153551c6b82942a4ebe056b909\"},\"headline\":\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l\",\"datePublished\":\"2025-05-11T13:16:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/\"},\"wordCount\":526,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/numero-de-bastidor-coche.jpg\",\"articleSection\":[\"N\u00daMERO DE BASTIDOR DE FORD\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/\",\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/\",\"name\":\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/numero-de-bastidor-coche.jpg\",\"datePublished\":\"2025-05-11T13:16:11+00:00\",\"description\":\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l \u00bfD\u00f3nde se encuentra el n\u00famero de bastidor o n\u00famero de chasis de tu coche?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#primaryimage\",\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/numero-de-bastidor-coche.jpg\",\"contentUrl\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/numero-de-bastidor-coche.jpg\",\"width\":1920,\"height\":971,\"caption\":\"numero de bastidor coche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#website\",\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/\",\"name\":\"Informaci\u00f3n b\u00e1stidor\",\"description\":\"Informaci\u00f3n b\u00e1stidor de coches\",\"publisher\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#organization\",\"name\":\"Donde est\u00e1 el bastidor\",\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/numero-de-bastidor-coche.jpg\",\"contentUrl\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/numero-de-bastidor-coche.jpg\",\"width\":1920,\"height\":971,\"caption\":\"Donde est\u00e1 el bastidor\"},\"image\":{\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/#\\\/schema\\\/person\\\/db138b153551c6b82942a4ebe056b909\",\"name\":\"buyhouseweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/litespeed\\\/avatar\\\/7cc686a90b46a5758b0b7f253437bac8.jpg?ver=1788033065\",\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/litespeed\\\/avatar\\\/7cc686a90b46a5758b0b7f253437bac8.jpg?ver=1788033065\",\"contentUrl\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/wp-content\\\/litespeed\\\/avatar\\\/7cc686a90b46a5758b0b7f253437bac8.jpg?ver=1788033065\",\"caption\":\"buyhouseweb\"},\"sameAs\":[\"https:\\\/\\\/info-coches.com\\\/bastidor\"],\"url\":\"https:\\\/\\\/info-coches.com\\\/bastidor\\\/author\\\/buyhouseweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l","description":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l \u00bfD\u00f3nde se encuentra el n\u00famero de bastidor o n\u00famero de chasis de tu coche?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/","og_locale":"es_ES","og_type":"article","og_title":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l","og_description":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l \u00bfD\u00f3nde se encuentra el n\u00famero de bastidor o n\u00famero de chasis de tu coche?","og_url":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/","og_site_name":"Informaci\u00f3n b\u00e1stidor","article_published_time":"2025-05-11T13:16:11+00:00","og_image":[{"width":1920,"height":971,"url":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","type":"image\/jpeg"}],"author":"buyhouseweb","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"buyhouseweb","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#article","isPartOf":{"@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/"},"author":{"name":"buyhouseweb","@id":"https:\/\/info-coches.com\/bastidor\/#\/schema\/person\/db138b153551c6b82942a4ebe056b909"},"headline":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l","datePublished":"2025-05-11T13:16:11+00:00","mainEntityOfPage":{"@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/"},"wordCount":526,"commentCount":0,"publisher":{"@id":"https:\/\/info-coches.com\/bastidor\/#organization"},"image":{"@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#primaryimage"},"thumbnailUrl":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","articleSection":["N\u00daMERO DE BASTIDOR DE FORD"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/","url":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/","name":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l","isPartOf":{"@id":"https:\/\/info-coches.com\/bastidor\/#website"},"primaryImageOfPage":{"@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#primaryimage"},"image":{"@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#primaryimage"},"thumbnailUrl":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","datePublished":"2025-05-11T13:16:11+00:00","description":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l \u00bfD\u00f3nde se encuentra el n\u00famero de bastidor o n\u00famero de chasis de tu coche?","breadcrumb":{"@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#primaryimage","url":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","contentUrl":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","width":1920,"height":971,"caption":"numero de bastidor coche"},{"@type":"BreadcrumbList","@id":"https:\/\/info-coches.com\/bastidor\/donde-esta-el-numero-de-bastidor-en-el-ford-taurus-l\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/info-coches.com\/bastidor\/"},{"@type":"ListItem","position":2,"name":"Donde est\u00e1 el n\u00famero de bastidor en el Ford Taurus l"}]},{"@type":"WebSite","@id":"https:\/\/info-coches.com\/bastidor\/#website","url":"https:\/\/info-coches.com\/bastidor\/","name":"Informaci\u00f3n b\u00e1stidor","description":"Informaci\u00f3n b\u00e1stidor de coches","publisher":{"@id":"https:\/\/info-coches.com\/bastidor\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/info-coches.com\/bastidor\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/info-coches.com\/bastidor\/#organization","name":"Donde est\u00e1 el bastidor","url":"https:\/\/info-coches.com\/bastidor\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/info-coches.com\/bastidor\/#\/schema\/logo\/image\/","url":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","contentUrl":"https:\/\/info-coches.com\/bastidor\/wp-content\/uploads\/2022\/02\/numero-de-bastidor-coche.jpg","width":1920,"height":971,"caption":"Donde est\u00e1 el bastidor"},"image":{"@id":"https:\/\/info-coches.com\/bastidor\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/info-coches.com\/bastidor\/#\/schema\/person\/db138b153551c6b82942a4ebe056b909","name":"buyhouseweb","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/info-coches.com\/bastidor\/wp-content\/litespeed\/avatar\/7cc686a90b46a5758b0b7f253437bac8.jpg?ver=1788033065","url":"https:\/\/info-coches.com\/bastidor\/wp-content\/litespeed\/avatar\/7cc686a90b46a5758b0b7f253437bac8.jpg?ver=1788033065","contentUrl":"https:\/\/info-coches.com\/bastidor\/wp-content\/litespeed\/avatar\/7cc686a90b46a5758b0b7f253437bac8.jpg?ver=1788033065","caption":"buyhouseweb"},"sameAs":["https:\/\/info-coches.com\/bastidor"],"url":"https:\/\/info-coches.com\/bastidor\/author\/buyhouseweb\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/posts\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/comments?post=256"}],"version-history":[{"count":0,"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/posts\/256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/media\/794"}],"wp:attachment":[{"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/media?parent=256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/categories?post=256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/info-coches.com\/bastidor\/wp-json\/wp\/v2\/tags?post=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}